{"id":10500,"date":"2026-05-05T13:42:37","date_gmt":"2026-05-05T06:42:37","guid":{"rendered":"http:\/\/www.hy.ac.th\/webwp\/?p=10500"},"modified":"2026-05-08T13:46:21","modified_gmt":"2026-05-08T06:46:21","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a-2","status":"publish","type":"post","link":"http:\/\/www.hy.ac.th\/webwp\/2026\/05\/05\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a-2\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2569"},"content":{"rendered":"\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2569 <br>\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2569 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e27\u0e31\u0e0d\u0e19\u0e49\u0e2d\u0e07\u0e2a\u0e39\u0e48\u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e32\u0e27\u0e41\u0e14\u0e07 \u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e38\u0e44\u0e23\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e27\u0e32\u0e17\u0e41\u0e25\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e19\u0e34\u0e25 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 9 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14<\/p>\n\n\n\n<p>\u0e0a\u0e48\u0e27\u0e07\u0e1a\u0e48\u0e32\u0e22 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2569 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01 \u0e19\u0e32\u0e22\u0e2a\u0e21\u0e21\u0e32\u0e23\u0e16 \u0e1c\u0e14\u0e38\u0e07\u0e2d\u0e23\u0e23\u0e16 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e38\u0e44\u0e23\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1e\u0e1a\u0e1b\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e19\u0e34\u0e25 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 9 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e1b\u0e30\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e04\u0e23\u0e39\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 9<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/www.hy.ac.th\/webwp\/wp-content\/uploads\/photo-gallery\/HYnews2026\/20260505-3.jpg?bwg=1778215201\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/www.hy.ac.th\/webwp\/wp-content\/uploads\/photo-gallery\/HYnews2026\/20260505-2.jpg?bwg=1778215201\" alt=\"\"\/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2569  \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2569 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e19\u0e34\u0e25 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 9 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14<\/p>\n","protected":false},"author":1,"featured_media":10467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"no_sidebar_full_width","colormag_page_sidebar_layout":"no_sidebar","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31,3],"tags":[],"class_list":["post-10500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-participation_news","category-hynews"],"jetpack_featured_media_url":"http:\/\/www.hy.ac.th\/webwp\/wp-content\/uploads\/2026\/05\/hy202605051.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/posts\/10500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/comments?post=10500"}],"version-history":[{"count":2,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/posts\/10500\/revisions"}],"predecessor-version":[{"id":10502,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/posts\/10500\/revisions\/10502"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/media\/10467"}],"wp:attachment":[{"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/media?parent=10500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/categories?post=10500"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.hy.ac.th\/webwp\/wp-json\/wp\/v2\/tags?post=10500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}